﻿{"id":100997,"date":"2016-12-20T14:04:12","date_gmt":"2016-12-20T12:04:12","guid":{"rendered":"http:\/\/www.viatgeaddictes.com\/blog\/?p=997"},"modified":"2017-02-08T20:23:05","modified_gmt":"2017-02-08T18:23:05","slug":"australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia","status":"publish","type":"post","link":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/","title":{"rendered":"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png\" alt=\"\" width=\"110\" height=\"60\" class=\"alignleft size-full wp-image-1000\" \/>El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds, sobre todo en la recogida de fruta, tras las presiones de los sectores agr\u00edcola y tur\u00edstico.<\/p>\n<p>De todos modos, la decisi\u00f3n supone la segunda rebaja de la propuesta inicial del Gobierno de la coalici\u00f3n conservadora, que en 2015 propuso una tasa del 32,5 por ciento y en septiembre la redujo al 19 por ciento.<\/p>\n<p>Esa primera rebaja fue rechazada en el Senado, donde la oposici\u00f3n laborista defiende situar la tasa en un 10,5 por ciento al considerar que una mayor presi\u00f3n fiscal podr\u00eda ahuyentar a los turistas, ya que son muchos los viajeros que utilizan esta f\u00f3rmula para pagarse su estancia en el pa\u00eds.<br \/>\n<!--more--><br \/>\nEl Gobierno acord\u00f3 con las fuerzas minoritarias la nueva tasa del 15 por ciento, que se aplicar\u00e1 a las rentas anuales menores de 37.000 d\u00f3lares australianos (27.627 d\u00f3lares estadounidenses o 25.878 euros) que perciban los <em>mochileros<\/em>.<\/p>\n<p>El jefe de la oficina del Tesoro, Scott Morrison, dijo que el acuerdo supondr\u00e1 una reducci\u00f3n de ingresos de unos 120 millones de d\u00f3lares locales (89,5 millones de d\u00f3lares o 83,9 millones de euros) en los pr\u00f3ximos cuatro a\u00f1os.<\/p>\n<p>Hasta ahora estos viajeros han estado exentos de pagar impuestos cuando sus ganancias anuales fuesen inferiores a los 18.200 d\u00f3lares australianos (13.606 d\u00f3lares estadounidenses o 12.764 euros).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds, sobre todo en la recogida de fruta, tras las presiones de los sectores agr\u00edcola y tur\u00edstico. De todos modos, la decisi\u00f3n supone la segunda rebaja de la propuesta inicial del &#8230; <a title=\"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\" class=\"read-more\" href=\"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/\" aria-label=\"Leer m\u00e1s sobre AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[47,110],"tags":[51,52],"class_list":["post-100997","post","type-post","status-publish","format-standard","hentry","category-regulaciones","category-viajes","tag-australia","tag-oceania"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia<\/title>\n<meta name=\"description\" content=\"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\" \/>\n<meta property=\"og:description\" content=\"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/\" \/>\n<meta property=\"og:site_name\" content=\"&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Noticias de viajes y turismo\" \/>\n<meta property=\"article:publisher\" content=\"facebook.com\/viatgeaddictes\" \/>\n<meta property=\"article:author\" content=\"facebook.com\/viatgeaddictes\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-20T12:04:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-08T18:23:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png\" \/>\n<meta name=\"author\" content=\"Viatgeaddictes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@viatgeaddictes\" \/>\n<meta name=\"twitter:site\" content=\"@viatgeaddictes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viatgeaddictes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/\"},\"author\":{\"name\":\"Viatgeaddictes\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#\\\/schema\\\/person\\\/37801c6f1a42b1acccc2262e8b9fb40a\"},\"headline\":\"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\",\"datePublished\":\"2016-12-20T12:04:12+00:00\",\"dateModified\":\"2017-02-08T18:23:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/\"},\"wordCount\":251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#\\\/schema\\\/person\\\/37801c6f1a42b1acccc2262e8b9fb40a\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/AU-128.png\",\"keywords\":[\"Australia\",\"Ocean\u00eda\"],\"articleSection\":[\"Regulaciones\",\"Viajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/\",\"url\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/\",\"name\":\"AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/AU-128.png\",\"datePublished\":\"2016-12-20T12:04:12+00:00\",\"dateModified\":\"2017-02-08T18:23:05+00:00\",\"description\":\"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/AU-128.png\",\"contentUrl\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/AU-128.png\",\"width\":128,\"height\":64},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/2016\\\/12\\\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/\",\"name\":\"Viatgeaddictes - Blog de noticias de viajes y turismo\",\"description\":\"Viatgeaddictes.com, recursos para el viajero independiente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#\\\/schema\\\/person\\\/37801c6f1a42b1acccc2262e8b9fb40a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/#\\\/schema\\\/person\\\/37801c6f1a42b1acccc2262e8b9fb40a\",\"name\":\"Viatgeaddictes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-viatgeaddictes-logo-350.png\",\"url\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-viatgeaddictes-logo-350.png\",\"contentUrl\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-viatgeaddictes-logo-350.png\",\"width\":350,\"height\":121,\"caption\":\"Viatgeaddictes\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-viatgeaddictes-logo-350.png\"},\"sameAs\":[\"https:\\\/\\\/www.viatgeaddictes.com\",\"facebook.com\\\/viatgeaddictes\",\"instagram.com\\\/viatgeaddictes\",\"https:\\\/\\\/x.com\\\/viatgeaddictes\",\"youtube.com\\\/viatgeaddictes\"],\"url\":\"https:\\\/\\\/www.viatgeaddictes.com\\\/blog\\\/author\\\/viatgeaddictes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia","description":"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/","og_locale":"es_ES","og_type":"article","og_title":"AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia","og_description":"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,","og_url":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/","og_site_name":"&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Noticias de viajes y turismo","article_publisher":"facebook.com\/viatgeaddictes","article_author":"facebook.com\/viatgeaddictes","article_published_time":"2016-12-20T12:04:12+00:00","article_modified_time":"2017-02-08T18:23:05+00:00","og_image":[{"url":"http:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png","type":"","width":"","height":""}],"author":"Viatgeaddictes","twitter_card":"summary_large_image","twitter_creator":"@viatgeaddictes","twitter_site":"@viatgeaddictes","twitter_misc":{"Escrito por":"Viatgeaddictes","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#article","isPartOf":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/"},"author":{"name":"Viatgeaddictes","@id":"https:\/\/www.viatgeaddictes.com\/blog\/#\/schema\/person\/37801c6f1a42b1acccc2262e8b9fb40a"},"headline":"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia","datePublished":"2016-12-20T12:04:12+00:00","dateModified":"2017-02-08T18:23:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/"},"wordCount":251,"commentCount":0,"publisher":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/#\/schema\/person\/37801c6f1a42b1acccc2262e8b9fb40a"},"image":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png","keywords":["Australia","Ocean\u00eda"],"articleSection":["Regulaciones","Viajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/","url":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/","name":"AUSTRALIA - Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia","isPartOf":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#primaryimage"},"image":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png","datePublished":"2016-12-20T12:04:12+00:00","dateModified":"2017-02-08T18:23:05+00:00","description":"El Gobierno australiano acord\u00f3 semanas atr\u00e1s fijar un impuesto del 15% que gravar\u00e1 a los viajeros extranjeros que trabajen durante su estancia en el pa\u00eds,","breadcrumb":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#primaryimage","url":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png","contentUrl":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2017\/01\/AU-128.png","width":128,"height":64},{"@type":"BreadcrumbList","@id":"https:\/\/www.viatgeaddictes.com\/blog\/2016\/12\/australia-se-cobrara-un-impuesto-a-los-mochileros-que-trabajen-para-pagarse-su-estancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.viatgeaddictes.com\/blog\/"},{"@type":"ListItem","position":2,"name":"AUSTRALIA &#8211; Se cobrar\u00e1 un impuesto a los mochileros que trabajen para pagarse su estancia"}]},{"@type":"WebSite","@id":"https:\/\/www.viatgeaddictes.com\/blog\/#website","url":"https:\/\/www.viatgeaddictes.com\/blog\/","name":"Viatgeaddictes - Blog de noticias de viajes y turismo","description":"Viatgeaddictes.com, recursos para el viajero independiente","publisher":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/#\/schema\/person\/37801c6f1a42b1acccc2262e8b9fb40a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viatgeaddictes.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/www.viatgeaddictes.com\/blog\/#\/schema\/person\/37801c6f1a42b1acccc2262e8b9fb40a","name":"Viatgeaddictes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2026\/05\/cropped-viatgeaddictes-logo-350.png","url":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2026\/05\/cropped-viatgeaddictes-logo-350.png","contentUrl":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2026\/05\/cropped-viatgeaddictes-logo-350.png","width":350,"height":121,"caption":"Viatgeaddictes"},"logo":{"@id":"https:\/\/www.viatgeaddictes.com\/blog\/wp-content\/uploads\/2026\/05\/cropped-viatgeaddictes-logo-350.png"},"sameAs":["https:\/\/www.viatgeaddictes.com","facebook.com\/viatgeaddictes","instagram.com\/viatgeaddictes","https:\/\/x.com\/viatgeaddictes","youtube.com\/viatgeaddictes"],"url":"https:\/\/www.viatgeaddictes.com\/blog\/author\/viatgeaddictes\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/posts\/100997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/comments?post=100997"}],"version-history":[{"count":0,"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/posts\/100997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/media?parent=100997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/categories?post=100997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viatgeaddictes.com\/blog\/wp-json\/wp\/v2\/tags?post=100997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}